{"id":965,"date":"2017-11-10T00:01:18","date_gmt":"2017-11-10T03:01:18","guid":{"rendered":"http:\/\/aladaa.com.ar\/asiayafrica\/?p=965"},"modified":"2017-11-10T00:01:18","modified_gmt":"2017-11-10T03:01:18","slug":"convocatoria-mujeres-aborto-y-religiones-debates-peru-2017-18","status":"publish","type":"post","link":"https:\/\/aladaa.com.ar\/asiayafrica\/convocatoria-mujeres-aborto-y-religiones-debates-peru-2017-18\/","title":{"rendered":"Convocatoria: Mujeres, aborto y religiones: debates &#8230; Per\u00fa 2017-18"},"content":{"rendered":"<p><a href=\"https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2017\/11\/Captura-de-pantalla-de-2017-11-09-23-53-54.png\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"966\" data-permalink=\"https:\/\/aladaa.com.ar\/asiayafrica\/convocatoria-mujeres-aborto-y-religiones-debates-peru-2017-18\/captura-de-pantalla-de-2017-11-09-23-53-54\/\" data-orig-file=\"https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2017\/11\/Captura-de-pantalla-de-2017-11-09-23-53-54.png?fit=819%2C155&amp;ssl=1\" data-orig-size=\"819,155\" data-comments-opened=\"0\" data-image-title=\"Captura de pantalla de 2017-11-09 23-53-54\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2017\/11\/Captura-de-pantalla-de-2017-11-09-23-53-54.png?fit=720%2C136&amp;ssl=1\" class=\"alignleft wp-image-966 size-full\" src=\"https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2017\/11\/Captura-de-pantalla-de-2017-11-09-23-53-54.png?resize=720%2C136\" alt=\"Captura de pantalla de 2017-11-09 23-53-54\" width=\"720\" height=\"136\" srcset=\"https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2017\/11\/Captura-de-pantalla-de-2017-11-09-23-53-54.png?w=819&amp;ssl=1 819w, https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2017\/11\/Captura-de-pantalla-de-2017-11-09-23-53-54.png?resize=300%2C56&amp;ssl=1 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/a><\/p>\n<p>CONVOCATORIA PARA ART\u00cdCULOS<\/p>\n<p>MUJERES, ABORTO Y RELIGIONES: DEBATES SOBRE POL\u00cdTICA SEXUAL, SUBJETIVIDADES Y CAMPO RELIGIOSO. (PER\u00cdODO 2017-2018)<\/p>\n<p>El Programa de Estudios de G\u00e9nero (PEG) de la Universidad Nacional Mayor de San Marcos (Lima) y el Centro de la Mujer Peruana Flora Trist\u00e1n se complacen en convocar a acad\u00e9micos\/as y activistas a presentar art\u00edculos para nuestro proyecto editorial<strong> Mujeres, aborto y religiones: debates sobre pol\u00edtica sexual, subjetividades y campo religioso.<\/strong><\/p>\n<p><strong>Presentaci\u00f3n<\/strong><\/p>\n<p>A lo largo de las \u00faltimas d\u00e9cadas, cada vez hemos sido m\u00e1s conscientes que el aborto es un hecho social complejo cuyo campo es construido por un conjunto de procesos hist\u00f3ricos, culturales y pol\u00edticos, insertos en din\u00e1micas globales y locales, como por ejemplo la pobreza, la desigualdad, la salud p\u00fablica, la clandestinidad, la legalidad\/ilegalidad y tambi\u00e9n, sin duda, la religi\u00f3n, que determinan las caracter\u00edsticas de su ejercicio, su penalizaci\u00f3n y su despenalizaci\u00f3n. Consideramos que el aborto como hecho social es un s\u00edntoma de la infraestructura de la pol\u00edtica sexual, es decir, de los mecanismos por los cuales se construye la diferencia sexual en cada sociedad.\u00a0Por ello, para analizar la din\u00e1mica del aborto en las sociedades contempor\u00e1neas es crucial hacer un ejercicio geneal\u00f3gico con respecto a las miradas y respuestas de las mujeres frente al lugar \u201casignado\u201d a ellas, al de sus cuerpos y sin duda a sus aportes en el desarrollo de la ciudadan\u00eda. Aborto y mujeres es un binomio que despliega una multitud de fuerzas que siempre inician y concluyen en sus propios cuerpos.<\/p>\n<p>Numerosas investigaciones se\u00f1alan que las religiones han sido uno de estos \u00e1mbitos privilegiados para dichos procesos. Desde el debate post secular, claramente, las religiones no han dejado de influir ni en la historia de la gubernamentalidad ni en la construcci\u00f3n de formas concretas de subjetividad, en especial con relaci\u00f3n al aborto. Esta publicaci\u00f3n busca reflexionar, analizar y problematizar estas relaciones.<\/p>\n<p>Las religiones pueden ser analizadas como lugar de control o tambi\u00e9n como un lugar de agencia (o ambos a la vez) en relaci\u00f3n con la construcci\u00f3n de las demandas (espirituales, pol\u00edticas, culturales, de derechos humanos) de las mujeres. En ese sentido, estudiar el fen\u00f3meno religioso desde una perspectiva de g\u00e9nero interseccional es una manera de rastrear la situaci\u00f3n de las mujeres en la actualidad, en especial a trav\u00e9s del an\u00e1lisis de las condiciones en las cuales las mujeres abortan. Por ello, nos interesa en particular indagar sobre aquellos procesos hist\u00f3ricos, pol\u00edticos y sociales en los cuales las religiones se muestran en contra o a favor del aborto y sus consecuencias en las vidas de las mujeres. Buscamos trabajos que indaguen profundamente en alguno de estos aspectos (o en ambos) con base en el an\u00e1lisis de material hist\u00f3rico, etnogr\u00e1fico, jur\u00eddico, entre otros. Nos interesa indagar la interacci\u00f3n existente entre diversas tradiciones religiosas (por ejemplo, el cristianismo, el juda\u00edsmo, el islam, el hinduismo, cosmovisiones ind\u00edgenas, entre otras) y dicho fen\u00f3meno.<\/p>\n<p>Esta convocatoria est\u00e1 dirigida a buscar trabajos que analicen el papel que juegan las religiones en la historia de la gubernamentalidad entorno al aborto. Es decir, se busca estudiar los mecanismos, las estrategias, las representaciones (entre otros), desarrollados por los campos y capitales religiosos, que est\u00e1n presentes en los procesos de influencia e intervenci\u00f3n del discurso religioso en los estados y tambi\u00e9n en la pol\u00edtica internacional (organismos multilaterales, cooperaci\u00f3n internacional) en el mundo contempor\u00e1neo.<\/p>\n<p>Esta convocatoria tambi\u00e9n est\u00e1 dirigida a analizar la construcci\u00f3n de corporalidades, subjetividades e identidades de aquellas mujeres que han pasado por experiencias de aborto, en relaci\u00f3n con los campos y capitales religiosos. Espec\u00edficamente, sus pr\u00e1cticas espirituales y\/o religiosaso ateas, sus experiencias y sus percepciones. Dentro de este \u00e1mbito, podemos contar con estudios referidos a cosmovisiones\/teolog\u00edas, ritos, m\u00edstica, moral y memoria. Tambi\u00e9n nos interesa explorar art\u00edculos que reflexionen sobre grupos y colectivos religiosos que se vinculan a experiencias de aborto, ya sea de manera positiva o negativa.<\/p>\n<p>M\u00e1s all\u00e1 del debate post secular, el encuentro con las religiones en el escenario internacional nos conduce a pensar sobre din\u00e1micas pol\u00edticas y nuevas construcciones subjetivas, donde las religiones se muestran como un dispositivo importante dentro del an\u00e1lisis social. En este sentido, nos interesa sobremanera indagar sobre la agencia de las mujeres o movimientos de mujeres (por ejemplo, feministas isl\u00e1micas, cat\u00f3licas, cristianas, jud\u00edas o creencias alternativas) que han pasado por experiencias de aborto dentro de sus propias tradiciones espirituales y pr\u00e1cticas ritualizadas,en cada contexto cultural y social, donde cada tradici\u00f3n se ve transformada por sus propias demandas.<\/p>\n<p>Objetivos<\/p>\n<p>1.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Construir una mirada comparativa y sistem\u00e1tica de la relaci\u00f3n entre discursos religiosos y aborto en las sociedades contempor\u00e1neas.<\/p>\n<p>2.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Analizar la construcci\u00f3n de las subjetividades de mujeres con experiencias de aborto en relaci\u00f3n con el fen\u00f3meno religioso dentro de contextos locales y regionales espec\u00edficos.<\/p>\n<p>3.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Estudiar las din\u00e1micas hist\u00f3ricas, sociales y culturales en las cuales las tradiciones religiosas cumplen un papel relevante en la promoci\u00f3n o el rechazo al acceso al aborto en las sociedades contempor\u00e1neas.<\/p>\n<p>4.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Reflexionar sobre las producciones espirituales (pr\u00e1cticas, rituales, percepciones, entre otras) desarrolladas por mujeres con experiencias de aborto en diversas regiones del mundo dentro o fuera de cada tradici\u00f3n religiosa, con especial \u00e9nfasis en el di\u00e1logo Sur-Sur.<\/p>\n<p>Tem\u00e1ticas<\/p>\n<p>Los art\u00edculos pueden insertarse dentro de estas l\u00edneas tem\u00e1ticas, aunque no son de car\u00e1cter excluyentes:<\/p>\n<p>1.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Tradiciones religiosas (cristianismo, juda\u00edsmo, islam, hinduismo, sinto\u00edsmo, tao\u00edsmo, cosmovisiones ind\u00edgenas, entre otras), aborto y mujeres en las sociedades contempor\u00e1neas.<\/p>\n<p>2.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Historia locales sobre la relaci\u00f3n entre aborto y mujeres dentro de cada tradici\u00f3n religiosa.<\/p>\n<p>3.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Mecanismos, estrategias y representaciones elaboradas por los l\u00edderes religiosos o los discursos religiosos que intervengan o influyan en la penalizaci\u00f3n o legalizaci\u00f3n del aborto en los estados o la pol\u00edtica internacional.<\/p>\n<p>4.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Pr\u00e1cticas espirituales de las mujeres en torno al aborto en las sociedades contempor\u00e1neas, en especial los di\u00e1logos y resistencias con las propias tradiciones religiosas.<\/p>\n<p>5.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0An\u00e1lisis sobre alg\u00fan aspecto de las pr\u00e1cticas espirituales (como la divinidad y la ritualidad) desde una perspectiva teol\u00f3gica feminista.<\/p>\n<p>6.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Producci\u00f3n teol\u00f3gica feminista sobre aborto y mujeres en cada tradici\u00f3n religiosa.<\/p>\n<p>7.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Capacidad de agencia de mujeres o grupos de mujeres en el \u00e1mbito de la producci\u00f3n espiritual en torno al aborto.<\/p>\n<p>8.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Expresiones espirituales ligadas a pr\u00e1cticas no confesionales, secularismo, ate\u00edsmo y otras manifestaciones espirituales contempor\u00e1neas en torno al aborto.<\/p>\n<p>9.\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Intersecci\u00f3n entre pr\u00e1cticas religiosas con sexualidad, g\u00e9nero, raza y clase social en el movimiento de mujeres.<\/p>\n<p>10.\u00a0\u00a0\u00a0\u00a0Relaci\u00f3n entre producci\u00f3n espiritual, discursos \u00e9ticos y pr\u00e1cticas solidarias desde las mujeres, con especial \u00e9nfasis en el di\u00e1logo Sur-Sur.<\/p>\n<p>Datos relevantes<\/p>\n<p>Para poder participar de esta convocatoria, las personas interesadas deber\u00e1n enviar un resumen de m\u00e1ximo 350 palabras en espa\u00f1ol o ingl\u00e9s, hasta el 30 de noviembre de 2017 a Martin Jaime (<a href=\"mailto:mjaimeb@pucp.pe\" target=\"_blank\">mjaimeb@pucp.pe<\/a>) y F\u00e1tima Valdivia (<a href=\"mailto:valdiviadelrio@gmail.com\" target=\"_blank\">valdiviadelrio@gmail.com<\/a>), editores acad\u00e9micos de esta compilaci\u00f3n. Cualquier consulta o pregunta, dirigirla a los mismos correos.<\/p>\n<p>Una vez que se comunique la aceptaci\u00f3n de las propuestas, los art\u00edculos seguir\u00e1n el modelo APA (American Psychiatry Association) y su extensi\u00f3n ser\u00e1 entre 8.000 y 10.000 palabras, sin incluir bibliograf\u00eda. Posteriormente, ser\u00e1n sometidos a revisi\u00f3n por pares doble ciego. Los art\u00edculos pueden ser escritos en ingl\u00e9s o espa\u00f1ol. Los art\u00edculos completos deber\u00e1n ser enviados hasta el 30 de junio de 2018 a Martin Jaime y F\u00e1tima Valdivia, editores acad\u00e9micos de esta compilaci\u00f3n, a los correos <a href=\"mailto:mjaimeb@pucp.pe\" target=\"_blank\">mjaimeb@pucp.pe<\/a> y <a href=\"mailto:valdiviadelrio@gmail.com\" target=\"_blank\">valdiviadelrio@gmail.com<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CONVOCATORIA PARA ART\u00cdCULOS MUJERES, ABORTO Y RELIGIONES: DEBATES SOBRE POL\u00cdTICA SEXUAL, SUBJETIVIDADES Y CAMPO RELIGIOSO. (PER\u00cdODO 2017-2018) El Programa de Estudios de G\u00e9nero (PEG) de la Universidad Nacional Mayor de San Marcos (Lima) y el Centro de la Mujer Peruana Flora Trist\u00e1n se complacen en&hellip; <br \/><a class=\"more-link\" href=\"https:\/\/aladaa.com.ar\/asiayafrica\/convocatoria-mujeres-aborto-y-religiones-debates-peru-2017-18\/\">Continue reading <span class=\"screen-reader-text\">Convocatoria: Mujeres, aborto y religiones: debates &#8230; Per\u00fa 2017-18<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8,5],"tags":[],"class_list":["post-965","post","type-post","status-publish","format-standard","hentry","category-internacionales","category-noticias"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9LsG3-fz","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":345,"url":"https:\/\/aladaa.com.ar\/asiayafrica\/asia-america-latina-convocatoria\/","url_meta":{"origin":965,"position":0},"title":"Asia Am\u00e9rica Latina &#8211; Convocatoria","author":"AladaaAr","date":"09\/04\/2016","format":false,"excerpt":"Convocatoria para art\u00edculos Asia\u00a0Am\u00e9rica\u00a0Latina\u00a0es una revista que promueve y difunde estudios acad\u00e9micos relacionados con tem\u00e1ticas actuales de Asia y de Am\u00e9rica Latina mediante una publicaci\u00f3n digital peri\u00f3dica destinada a acad\u00e9micos del campo de las Ciencias Sociales y las Humanidades. Asia Am\u00e9rica Latina\u00a0busca convertirse en un emprendimiento acad\u00e9mico de calidad e\u2026","rel":"","context":"En &quot;Internacionales&quot;","block_context":{"text":"Internacionales","link":"https:\/\/aladaa.com.ar\/asiayafrica\/category\/internacionales\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":940,"url":"https:\/\/aladaa.com.ar\/asiayafrica\/conf-los-usos-politicos-del-yoga-usal\/","url_meta":{"origin":965,"position":1},"title":"Conf.: Los usos politicos del yoga. USAL","author":"AladaaAr","date":"06\/10\/2017","format":false,"excerpt":"CONFERENCIA \u201cLos usos pol\u00edticos del yoga\u201d Dr. Adri\u00e1n Mu\u00f1oz (El Colegio de M\u00e9xico - UNAM) Lunes 9 de octubre de 18 a 20 hs. FFLEO \u2013 Aula Magna (Lavalle 1878, 1\u00b0 piso) Invitan: Facultad de Filosof\u00eda Letras y Estudios Orientales, Universidad del Salvador y Proyecto de Investigaci\u00f3n (VRID-1658) \u201cFilosof\u00eda de\u2026","rel":"","context":"En &quot;Nacionales&quot;","block_context":{"text":"Nacionales","link":"https:\/\/aladaa.com.ar\/asiayafrica\/category\/nacionales\/"},"img":{"alt_text":"Flyer Conferencia Adri\u00e1n","src":"https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2017\/10\/Flyer-Conferencia-Adri%C3%A1n-300x225.png?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":1551,"url":"https:\/\/aladaa.com.ar\/asiayafrica\/taller-conflictos-y-transformacion-social-en-medio-oriente-espacio-tiempo-caba\/","url_meta":{"origin":965,"position":2},"title":"Taller: Conflictos y transformaci\u00f3n social en Medio Oriente, Espacio Tiempo, CABA","author":"AladaaAr","date":"19\/07\/2018","format":false,"excerpt":"Taller: Conflictos y transformaci\u00f3n social en Medio Oriente Por Carolina Bracco Duraci\u00f3n: 12 horas total. 1 encuentro semanal de 3hs, 4 encuentros. Inicio: martes 7 de agosto, desde las 18 hasta las 21 hs. Fin: martes 28 de agosto. Valor: $ 1500 \/ 50% de descuento para socias y socios.\u2026","rel":"","context":"En &quot;Nacionales&quot;","block_context":{"text":"Nacionales","link":"https:\/\/aladaa.com.ar\/asiayafrica\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2018\/07\/Tiempo_Islam-300x283.jpg?resize=350%2C200","width":350,"height":200},"classes":[]},{"id":563,"url":"https:\/\/aladaa.com.ar\/asiayafrica\/convocatoria-contra-relatos-desde-el-sur\/","url_meta":{"origin":965,"position":3},"title":"Convocatoria Contra | Relatos desde el Sur","author":"AladaaAr","date":"23\/08\/2016","format":false,"excerpt":"CONTRA | RELATOS desde el Sur Apuntes sobre \u00c1frica y Medio\u00a0 Oriente Convoca a presentaci\u00f3n\u00a0 de art\u00edculos in\u00e9ditos y\u00a0 rese\u00f1as\u00a0 para su pr\u00f3xima\u00a0 edici\u00f3n A\u00f1o XII,\u00a0 N\u00b0 14, diciembre 2016. CONTRA | RELATOS desde el Sur es\u00a0 una publicaci\u00f3n semestral del Programa de Estudios\u00a0 Africanos y del Programa de\u00a0 Estudios\u2026","rel":"","context":"En &quot;Nacionales&quot;","block_context":{"text":"Nacionales","link":"https:\/\/aladaa.com.ar\/asiayafrica\/category\/nacionales\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":936,"url":"https:\/\/aladaa.com.ar\/asiayafrica\/conf-literatura-yoguica-composicion-y-transmision-uba\/","url_meta":{"origin":965,"position":4},"title":"Conf.: Literatura yoguica, composicion y transmision, UBA","author":"AladaaAr","date":"06\/10\/2017","format":false,"excerpt":"Conferencia - Taller \"LITERATURA Y\u00d3GUICA: PROCESOS DE COMPOSICI\u00d3N Y TRANSMISI\u00d3N\", que dictar\u00e1 el Dr. Adri\u00e1n Mu\u00f1oz\u00a0el mi\u00e9rcoles 11, de 14 a 17 hs., en la Sala del Consejo directivo de la Facultad de Filosof\u00eda y Letras de la Universidad de Buenos Aires (Pu\u00e1n 480, 2\u00b0 Piso). El Instituto de Filolog\u00eda\u2026","rel":"","context":"En &quot;Nacionales&quot;","block_context":{"text":"Nacionales","link":"https:\/\/aladaa.com.ar\/asiayafrica\/category\/nacionales\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":642,"url":"https:\/\/aladaa.com.ar\/asiayafrica\/convocatoria-revista-al-zeytun\/","url_meta":{"origin":965,"position":5},"title":"Convocatoria Revista Al Zeytun","author":"AladaaAr","date":"22\/12\/2016","format":false,"excerpt":"ATENCI\u00d3N: PR\u00d3RROGA HASTA EL 10 DE ENERO DE 2017 Convocatoria para la presentaci\u00f3n de art\u00edculos acad\u00e9micos Revista Al Zeytun \u00a0A\u00f1o 1, N\u00ba 1 - Primer Semestre 2017 La Embajada del Estado de Palestina con el apoyo de CLACSO convoca a la presentaci\u00f3n de art\u00edculos para su revista Al Zeytun. Al\u2026","rel":"","context":"En &quot;Nacionales&quot;","block_context":{"text":"Nacionales","link":"https:\/\/aladaa.com.ar\/asiayafrica\/category\/nacionales\/"},"img":{"alt_text":"Convocatoria articulos Al Zeytun","src":"https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2016\/10\/unnamed-1024x635.jpg?resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2016\/10\/unnamed-1024x635.jpg?resize=350%2C200 1x, https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2016\/10\/unnamed-1024x635.jpg?resize=525%2C300 1.5x"},"classes":[]}],"_links":{"self":[{"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/posts\/965","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/comments?post=965"}],"version-history":[{"count":1,"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/posts\/965\/revisions"}],"predecessor-version":[{"id":967,"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/posts\/965\/revisions\/967"}],"wp:attachment":[{"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/media?parent=965"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/categories?post=965"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/tags?post=965"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}