{"id":1556,"date":"2018-07-19T00:44:27","date_gmt":"2018-07-19T03:44:27","guid":{"rendered":"http:\/\/aladaa.com.ar\/asiayafrica\/?p=1556"},"modified":"2018-07-19T00:44:27","modified_gmt":"2018-07-19T03:44:27","slug":"en-linea-revista-desafios-u-del-rosario-colombia","status":"publish","type":"post","link":"https:\/\/aladaa.com.ar\/asiayafrica\/en-linea-revista-desafios-u-del-rosario-colombia\/","title":{"rendered":"En l\u00ednea revista Desaf\u00edos, U. del Rosario, Colombia"},"content":{"rendered":"<div dir=\"ltr\">Estimados\/as lectores\/as:<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Desaf\u00edos acaba de publicar su \u00faltimo n\u00famero en<\/div>\n<div dir=\"ltr\"><a href=\"https:\/\/revistas.urosario.edu.co\/index.php\/desafios.\" target=\"_blank\" rel=\"nofollow noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=es&amp;q=https:\/\/revistas.urosario.edu.co\/index.php\/desafios.&amp;source=gmail&amp;ust=1532055402134000&amp;usg=AFQjCNEArX2ZhGdEKsqpPadlY-88GTlSDA\">https:\/\/revistas.urosario.edu.<wbr \/>co\/index.php\/desafios. <\/a>A continuaci\u00f3n le<\/div>\n<div dir=\"ltr\">mostramos la tabla de contenidos, despu\u00e9s puede visitar nuestro sitio web<\/div>\n<div dir=\"ltr\">para consultar los art\u00edculos que sean de su inter\u00e9s.<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Gracias por mantener el inter\u00e9s en nuestro trabajo,<\/div>\n<div dir=\"ltr\">Coordinaci\u00f3n Editorial<\/div>\n<div dir=\"ltr\">Universidad del Rosario<\/div>\n<div dir=\"ltr\"><a href=\"mailto:revistadesafios@urosario.edu.co\" target=\"_blank\" rel=\"nofollow noopener\">revistadesafios@urosario.edu.<wbr \/>co<\/a><\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Desaf\u00edos<\/div>\n<div dir=\"ltr\">Vol. 30, N\u00fam. 2 (2018): (julio-diciembre) Estado del arte de la Econom\u00eda<\/div>\n<div dir=\"ltr\">Pol\u00edtica Internacional en Latinoam\u00e9rica<\/div>\n<div dir=\"ltr\">Tabla de contenidos<\/div>\n<div dir=\"ltr\"><a href=\"https:\/\/revistas.urosario.edu.co\/index.php\/desafios\/issue\/view\/403\" target=\"_blank\" rel=\"nofollow noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=es&amp;q=https:\/\/revistas.urosario.edu.co\/index.php\/desafios\/issue\/view\/403&amp;source=gmail&amp;ust=1532055402134000&amp;usg=AFQjCNFfyob0tUMutvuL0sw75qv0mHThAg\">https:\/\/revistas.urosario.edu.<wbr \/>co\/index.php\/desafios\/issue\/<wbr \/>view\/403<\/a><\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\"><a href=\"https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2018\/07\/Captura-de-pantalla-190718-004017.png\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"1557\" data-permalink=\"https:\/\/aladaa.com.ar\/asiayafrica\/en-linea-revista-desafios-u-del-rosario-colombia\/captura-de-pantalla-190718-004017\/\" data-orig-file=\"https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2018\/07\/Captura-de-pantalla-190718-004017.png?fit=360%2C524&amp;ssl=1\" data-orig-size=\"360,524\" data-comments-opened=\"0\" data-image-title=\"Captura de pantalla &amp;#8211; 190718 &amp;#8211; 00:40:17\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2018\/07\/Captura-de-pantalla-190718-004017.png?fit=360%2C524&amp;ssl=1\" class=\"alignright size-medium wp-image-1557\" src=\"https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2018\/07\/Captura-de-pantalla-190718-004017-206x300.png?resize=206%2C300\" alt=\"\" width=\"206\" height=\"300\" srcset=\"https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2018\/07\/Captura-de-pantalla-190718-004017.png?resize=206%2C300&amp;ssl=1 206w, https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2018\/07\/Captura-de-pantalla-190718-004017.png?w=360&amp;ssl=1 360w\" sizes=\"auto, (max-width: 206px) 100vw, 206px\" \/><\/a><\/div>\n<div dir=\"ltr\">Editorial<\/div>\n<div dir=\"ltr\">&#8212;&#8212;&#8211;<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Dossier \u201cEstado del arte de la Econom\u00eda Pol\u00edtica Internacional en<\/div>\n<div dir=\"ltr\">Latinoam\u00e9rica\u201d<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Dossier Tem\u00e1tico<\/div>\n<div dir=\"ltr\">&#8212;&#8212;&#8211;<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">La Econom\u00eda Pol\u00edtica Internacional en el campo de las Relaciones<\/div>\n<div dir=\"ltr\">Internacionales argentinas (15-42)<\/div>\n<div dir=\"ltr\">\u00a0\u00a0\u00a0 Melisa Deciancio<\/div>\n<div dir=\"ltr\">Diplomacia financiera en la periferia global: entre la cooperaci\u00f3n y la<\/div>\n<div dir=\"ltr\">coerci\u00f3n. Aproximaciones te\u00f3rico-emp\u00edricas a partir de las relaciones<\/div>\n<div dir=\"ltr\">crediticias de Argentina con Venezuela y China (43-88)<\/div>\n<div dir=\"ltr\">\u00a0\u00a0\u00a0 Jos\u00e9 Marcelino Fern\u00e1ndez Alonso<\/div>\n<div dir=\"ltr\">Ideas y pol\u00edtica exterior econ\u00f3mica en el mundo en desarrollo. El caso de<\/div>\n<div dir=\"ltr\">la salida de Uruguay de las negociaciones del TiSA (89-126)<\/div>\n<div dir=\"ltr\">\u00a0\u00a0\u00a0 Nicol\u00e1s Pose Ferraro<\/div>\n<div dir=\"ltr\">El estado del arte de la Econom\u00eda Pol\u00edtica Internacional en Brasil:<\/div>\n<div dir=\"ltr\">posibilidades para pensar (y practicar) una EPI a partir de abajo (127-157)<\/div>\n<div dir=\"ltr\">\u00a0\u00a0\u00a0 Leonardo Ramos,\u00a0\u00a0\u00a0 Marina Scotelaro<\/div>\n<div dir=\"ltr\">Las Empresas Transnacionales: Un punto de encuentro para la Econom\u00eda<\/div>\n<div dir=\"ltr\">Pol\u00edtica Internacional de Am\u00e9rica Latina (159-190)<\/div>\n<div dir=\"ltr\">\u00a0\u00a0\u00a0 Marcelo Saguier,\u00a0\u00a0\u00a0 Luciana Ghiotto<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Secci\u00f3n General<\/div>\n<div dir=\"ltr\">&#8212;&#8212;&#8211;<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Reg\u00edmenes de pol\u00edtica social en Am\u00e9rica Latina: una revisi\u00f3n cr\u00edtica de<\/div>\n<div dir=\"ltr\">la literatura (193-235)<\/div>\n<div dir=\"ltr\">\u00a0\u00a0\u00a0 Florencia Ant\u00eda<\/div>\n<div dir=\"ltr\">Cuestionando consensos: algunos apuntes frente al \u2014\u00bfeventual?\u2014 ascenso<\/div>\n<div dir=\"ltr\">de los BRICS como poderes globales (237-278)<\/div>\n<div dir=\"ltr\">\u00a0\u00a0\u00a0 Javier Leonardo Garay Vargas<\/div>\n<div dir=\"ltr\">An\u00e1lisis de Pol\u00edtica P\u00fablica de Infancia y Adolescencia en Bogot\u00e1, D.<\/div>\n<div dir=\"ltr\">C., 2011-2021, Colombia (279-314)<\/div>\n<div dir=\"ltr\">\u00a0\u00a0\u00a0 Nathaly Rozo,\u00a0\u00a0\u00a0 Zulma Vargas Trujillo<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Rese\u00f1as Bibliogr\u00e1ficas<\/div>\n<div dir=\"ltr\">&#8212;&#8212;&#8211;<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Tassara, Carlo. Cooperaci\u00f3n internacional para el desarrollo: gobierno,<\/div>\n<div dir=\"ltr\">econom\u00eda y sociedad. Evoluci\u00f3n de las pol\u00edticas y escenarios futuros.<\/div>\n<div dir=\"ltr\">Bogot\u00e1: Ediciones Unisalle. 2016. 132 pp. (317-323)<\/div>\n<div dir=\"ltr\">\u00a0\u00a0\u00a0 Luca De Paoli<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Revista Desaf\u00ecos<\/div>\n<div dir=\"ltr\">Facultad de Ciencia Pol\u00edtica, Gobierno y Relaciones Internacionales<\/div>\n<div dir=\"ltr\">Universidad del Rosario<\/div>\n<div dir=\"ltr\">Carrera 6A <a href=\"https:\/\/maps.google.com\/?q=12C-13&amp;entry=gmail&amp;source=g\">12C-13<\/a>, Edificio Santaf\u00e9, oficina 206<\/div>\n<div dir=\"ltr\">Bogot\u00e1 D. C., Colombia<\/div>\n<div dir=\"ltr\">Tel\u00e9fono: (57 1) 2970200, extensi\u00f3n 3783<\/div>\n<div dir=\"ltr\">Celular: 57+ 316 4611516<\/div>\n<div dir=\"ltr\"><a href=\"mailto:revistadesafios@urosario.edu.co\" target=\"_blank\" rel=\"nofollow noopener\">revistadesafios@urosario.edu.<wbr \/>co<\/a><\/div>\n<div dir=\"ltr\">______________________________<wbr \/>_______________<\/div>\n<div dir=\"ltr\"><\/div>\n<div dir=\"ltr\">Desaf\u00edos<\/div>\n<div dir=\"ltr\"><a href=\"http:\/\/revistas.urosario.edu.co\/index.php\/desafios\" target=\"_blank\" rel=\"nofollow noopener\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=es&amp;q=http:\/\/revistas.urosario.edu.co\/index.php\/desafios&amp;source=gmail&amp;ust=1532055402134000&amp;usg=AFQjCNG8x7QZl4iZRuKYqRzRmvSS6tKfNQ\">http:\/\/revistas.urosario.edu.<wbr \/>co\/index.php\/desafios<\/a><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Estimados\/as lectores\/as: Desaf\u00edos acaba de publicar su \u00faltimo n\u00famero en https:\/\/revistas.urosario.edu.co\/index.php\/desafios. A continuaci\u00f3n le mostramos la tabla de contenidos, despu\u00e9s puede visitar nuestro sitio web para consultar los art\u00edculos que sean de su inter\u00e9s. Gracias por mantener el inter\u00e9s en nuestro trabajo, Coordinaci\u00f3n Editorial Universidad&hellip; <br \/><a class=\"more-link\" href=\"https:\/\/aladaa.com.ar\/asiayafrica\/en-linea-revista-desafios-u-del-rosario-colombia\/\">Continue reading <span class=\"screen-reader-text\">En l\u00ednea revista Desaf\u00edos, U. del Rosario, Colombia<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":1558,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[8,5],"tags":[10,149,27,107,61],"class_list":["post-1556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-internacionales","category-noticias","tag-china","tag-colombia","tag-economia","tag-geopolitica","tag-publicaciones"],"jetpack_featured_media_url":"https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2018\/07\/URosarioCo.png?fit=335%2C133&ssl=1","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p9LsG3-p6","jetpack_likes_enabled":true,"jetpack-related-posts":[{"id":428,"url":"https:\/\/aladaa.com.ar\/asiayafrica\/dossier-africa-un-continente-policromatico\/","url_meta":{"origin":1556,"position":0},"title":"DOSSIER \u00c1FRICA: UN CONTINENTE POLICROM\u00c1TICO","author":"AladaaAr","date":"26\/05\/2016","format":false,"excerpt":"DOSSIER \u00c1FRICA: UN CONTINENTE POLICROM\u00c1TICO El 25 de mayo se celebra en todo el mundo el D\u00eda de \u00c1frica. El origen de esta conmemoraci\u00f3n se remonta al a\u00f1o 1963, cuando treinta y dos l\u00edderes de Estados africanos se reunieron en Addis Abeba, para conformar la Organizaci\u00f3n de la Unidad Africana\u2026","rel":"","context":"En &quot;Nacionales&quot;","block_context":{"text":"Nacionales","link":"https:\/\/aladaa.com.ar\/asiayafrica\/category\/nacionales\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":408,"url":"https:\/\/aladaa.com.ar\/asiayafrica\/v-encuentro-latinoamericano-de-metodologia-de-las-ciencias-sociales\/","url_meta":{"origin":1556,"position":1},"title":"V Encuentro Latinoamericano de Metodolog\u00eda de las Ciencias Sociales","author":"AladaaAr","date":"14\/05\/2016","format":false,"excerpt":"V Encuentro Latinoamericano de Metodolog\u00eda de las Ciencias Sociales - M\u00e9todos, metodolog\u00edas y nuevas epistemolog\u00edas en las ciencias sociales: desaf\u00edos para el conocimiento profundo de Nuestra Am\u00e9rica Mendoza (Argentina), 16-18 de noviembre de 2016 SEGUNDA CIRCULAR 1. Presentaci\u00f3n En el IV Encuentro Latinoamericano de Metodolog\u00eda de las Ciencias Sociales (ELMeCS),\u2026","rel":"","context":"En &quot;Nacionales&quot;","block_context":{"text":"Nacionales","link":"https:\/\/aladaa.com.ar\/asiayafrica\/category\/nacionales\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":906,"url":"https:\/\/aladaa.com.ar\/asiayafrica\/sudafrica-post-apartheid-nacion-ciudadania-gobierno-movimientos-sociales-genero-y-sexualidade\/","url_meta":{"origin":1556,"position":2},"title":"Sud\u00e1frica post apartheid: naci\u00f3n, ciudadan\u00eda, gobierno, movimientos sociales, g\u00e9nero y sexualidades","author":"AladaaAr","date":"28\/08\/2017","format":false,"excerpt":"Estimados colegas, Enviamos a ustedes la informaci\u00f3n que nos hiciera llegar la Dra. M\u00f3nica Cejas (Maestr\u00eda en Estudios de la Mujer y Doctorado en Estudios Feministas, Departamento de Pol\u00edtica y Cultura, UNIVERSIDAD AUT\u00d3NOMA METROPOLITANA-XOCHIMILCO, M\u00e9xico), acerca del libro que acaba de publicarse este a\u00f1o bajo su coordinaci\u00f3n, sobre Sud\u00e1frica. El\u2026","rel":"","context":"En &quot;Internacionales&quot;","block_context":{"text":"Internacionales","link":"https:\/\/aladaa.com.ar\/asiayafrica\/category\/internacionales\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":1296,"url":"https:\/\/aladaa.com.ar\/asiayafrica\/jornada-g20-en-argentina-intereses-oportunidades-y-desafios\/","url_meta":{"origin":1556,"position":3},"title":"Jornada G20 en Argentina: Intereses, oportunidades y desaf\u00edos.","author":"AladaaAr","date":"18\/04\/2018","format":false,"excerpt":"Jornada G20 en Argentina: Intereses, oportunidades y desaf\u00edos. Mi\u00e9rcoles 2 de mayo de 14 a 20hs. Biblioteca Nacional. Entrada libre y gratuita. Vacantes limitadas. Exponen: Mariano Bartolom\u00e9, Juan Battaleme, Paulo Botta, Alberto Hutschenreuter, Jorge Malena, Silvia Perazzo, L\u00eda Rodr\u00edguez de la Vega. Informes: inscripciones@anu-ar.org Cierre de jornada: Vino de honor\u2026","rel":"","context":"En &quot;Nacionales&quot;","block_context":{"text":"Nacionales","link":"https:\/\/aladaa.com.ar\/asiayafrica\/category\/nacionales\/"},"img":{"alt_text":"","src":"https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2018\/04\/g20-1.jpg?fit=650%2C800&ssl=1&resize=350%2C200","width":350,"height":200,"srcset":"https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2018\/04\/g20-1.jpg?fit=650%2C800&ssl=1&resize=350%2C200 1x, https:\/\/i0.wp.com\/aladaa.com.ar\/asiayafrica\/wp-content\/uploads\/2018\/04\/g20-1.jpg?fit=650%2C800&ssl=1&resize=525%2C300 1.5x"},"classes":[]},{"id":308,"url":"https:\/\/aladaa.com.ar\/asiayafrica\/diplomado-en-teoria-y-practica-del-yoga-u-externado-colombia\/","url_meta":{"origin":1556,"position":4},"title":"Diplomado en Teor\u00eda y Pr\u00e1ctica del Yoga U. Externado, Colombia","author":"AladaaAr","date":"19\/03\/2016","format":false,"excerpt":"\"Los invito a \u00a0beneficiarse \u00a0de esta oportunidad. \u00a0Ir al encuentro de una tradici\u00f3n milenaria con alto nivel acad\u00e9mico.\u00a0 Con el respaldo de la Embajada de India en nuestro pa\u00eds, \u00a0la Universidad Externado de Colombia \u00a0y su Centro de Estudios sobre India Contempor\u00e1nea- CESICAM, dan inicio al \u00a0Diplomado en Teor\u00eda y\u2026","rel":"","context":"En &quot;Internacionales&quot;","block_context":{"text":"Internacionales","link":"https:\/\/aladaa.com.ar\/asiayafrica\/category\/internacionales\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]},{"id":926,"url":"https:\/\/aladaa.com.ar\/asiayafrica\/xi-congreso-nacional-de-estudios-coreanos-paralelo-38-en-el-siglo-xxi\/","url_meta":{"origin":1556,"position":5},"title":"XI Congreso Nacional de Estudios Coreanos &#8220;Paralelo 38 en el siglo XXI&#8221;","author":"AladaaAr","date":"04\/10\/2017","format":false,"excerpt":"Estudios Coreanos \/ Rosario, Argentina, Junio de 2018. Estimados Colegas El\u00a0Grupo de Estudios del Asia y el Pac\u00edfico\u00a0de la\u00a0Universidad Abierta Interamericana\u00a0tiene el orgullo de convocar a la presentaci\u00f3n de ponencias para el\u00a0XI Congreso Nacional de Estudios Coreanos \"Paralelo 38 en el siglo XXI\", el cual tendr\u00e1 lugar en nuestra sede\u2026","rel":"","context":"En &quot;Nacionales&quot;","block_context":{"text":"Nacionales","link":"https:\/\/aladaa.com.ar\/asiayafrica\/category\/nacionales\/"},"img":{"alt_text":"","src":"","width":0,"height":0},"classes":[]}],"_links":{"self":[{"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/posts\/1556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/comments?post=1556"}],"version-history":[{"count":1,"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/posts\/1556\/revisions"}],"predecessor-version":[{"id":1559,"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/posts\/1556\/revisions\/1559"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/media\/1558"}],"wp:attachment":[{"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/media?parent=1556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/categories?post=1556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aladaa.com.ar\/asiayafrica\/wp-json\/wp\/v2\/tags?post=1556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}